{"id":7845,"date":"2024-04-24T18:11:14","date_gmt":"2024-04-24T16:11:14","guid":{"rendered":"https:\/\/nziria.com\/?p=7845"},"modified":"2025-09-13T02:26:29","modified_gmt":"2025-09-13T00:26:29","slug":"lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs","status":"publish","type":"post","link":"https:\/\/nziria.com\/it\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/","title":{"rendered":"LOST IN THE DREAM: IL CAPOLAVORO DEI THE WAR ON DRUGS COMPIE 10 ANNI"},"content":{"rendered":"<div>\r\n<h3 class=\"wp-block-heading\">Milano, marzo 2014, tutto il giorno.<\/h3>\r\n<h3>Una timida primavera si affaccia alla finestra del terzo piano dell\u2019edificio in cui lavoro. Traffico, mezzi pubblici che vanno e vengono, il vociare dalla strada e il via-vai continuo di persone che transitano da via del Lazzaretto dirette in Stazione Centrale o verso Corso Buenos Aires.<\/h3>\r\n<h3>Ho 31 anni, sono distante centinaia di chilometri da dove sono nato e Milano \u00e8 diventata casa mia da tre anni e mezzo, ma non mi piace molto. Non mi \u00e8 mai piaciuta in verit\u00e0, anche se per un biennio ho nutrito per lei un certo senso di curiosit\u00e0 ed apertura, di quelli che provi verso i posti che non conosci ancora ma da cui sei in qualche modo attratto, in cui pensi di ambientarti e poter lontano dai tuoi. Al netto di alcune possibilit\u00e0 che indiscutibilmente mi ha offerto, mi accordo che s\u00ec, mi ci sono ambientato, ma Milano non esercita quasi pi\u00f9 alcun fascino su di me.<\/h3>\r\n<h3>Ho un altro ritmo rispetto a quel contesto urbano divorato dal cemento, immerso in uno scenario frenetico, efficiente, iperproduttivo ed economicamente pulsante, ma che alimenta in me un certo senso di distacco, di estraneit\u00e0 ed alienazione. Ho un altro senso di bellezza e tento di spiegarlo a coloro, non pochi, che mi dicono che Milano \u00e8 bella.<\/h3>\r\n<h3>Bella, davvero? In relazione a cosa? E come mai, se una parte di me mi trattiene qui, un\u2019altra sogna di andarsene?<\/h3>\r\n<\/div>\r\n<h2 style=\"text-align: center;\">IL DISCO<\/h2>\r\n\r\n\r\n\r\n<div style=\"text-align: center;\"><a href=\"https:\/\/youtu.be\/BijxWQluXE0?si=4cOu-HGdQEGzHRn5\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"text-align: start;\" src=\"https:\/\/media.pitchfork.com\/photos\/5929a63fb1335d7bf1698dad\/1:1\/w_450%2Cc_limit\/9419e472.jpg\" alt=\"L'immagine pu\u00f2 contenere Umano e Persona\" width=\"433\" height=\"433\" \/><\/a>\r\n<h3>\u00c8 un normale mercoled\u00ec in ufficio. Sono al PC e, tra un allenamento e l\u2019altro, vago distrattamente online e mi imbatto nella recensione di un album di una band che non conosco. L'album in questione \u00e8 <strong>\u201cPerso nel sogno\u201d<\/strong> di <strong>La guerra alla droga.<\/strong> Dice: \u201cPrenditi 60 minuti. E perdersi nel sogno.\u201d Incuriosito, mi metto le cuffie, apro il lettore un po' scettico e comincio a cercare informazioni sulla band. Non ho grandi aspettative, in realt\u00e0. Non ne ho mai sentito parlare, non ho mai avuto molta fiducia nella critica musicale, sempre alla frenetica ricerca di nuove forme di eccitazione musicale. \u201cSar\u00e0 l\u2019ennesima cosa pompata dalla stampa di settore\u201d, penso tra me. Mi sbaglio palesemente. Dopo pochi minuti, quella che pensavo potesse essere solo musica di sottofondo mi affascina completamente. La meraviglia si impossessa di me ed entro in uno stato di trance onirica.<\/h3>\r\n<h3>Fin dalle prime note dei brani d\u2019apertura, la cosa che mi colpisce \u00e8 la purezza del suono: liquido, stratificato, arioso, zeppo di echi, riverberi ed effetti decisamente inusuali per le mie orecchie. E\u2019 come una coltre sonora, in cui le tastiere spazio-ambiente si avvolgono raffinati ricami tra pianoforte e chitarra, trasportandomi in un\u2019atmosfera sospesa e senza tempo.<\/h3>\r\n<h3>Cerco di trovare paralleli, di cercare nella mia memoria di ascoltatore dei punti di riferimento che mi aiutino a decifrare meglio ci\u00f2 che sto ascoltando. Ho sentito riferimenti a <strong>Springsteen, Dire Straits, Tom Petty<\/strong>, un certo dreampop che fino ad allora avevo sempre tenuto in scarsa considerazione. Ma tutti i confronti non reggono da soli. Non si tratta di una copia carbone o di un&#039;opera derivata, in quanto tutte le fonti di ispirazione, pur evidenti, sono espresse in una forma assolutamente unica. Se infatti, da un lato, c&#039;\u00e8 un certo senso di familiarit\u00e0 con la classicit\u00e0 delle star e strips rock, sconfina invece nella psichedelia, in uno stile folk ampliato da atmosfere eteree e code ambient e shoegaze. E poi c&#039;\u00e8 la voce del cantante, <strong>Adam Granduciel<\/strong>che emerge chiara da quell\u2019impasto sonoro, con il suo timbro delicato che rende il tutto ancora pi\u00f9 sognante.<\/h3>\r\n<p>&nbsp;<\/p>\r\n<\/div>\r\n<div>\r\n<h3 style=\"text-align: center;\"><strong>UN OCEANO TRA LE ONDE<\/strong><\/h3>\r\n<figure style=\"width: 390px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/youtu.be\/BijxWQluXE0?si=4cOu-HGdQEGzHRn5\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/media.gq.com\/photos\/61794c706852e9e36c724474\/4:3\/w_1820,h_1365,c_limit\/The-War-on-Drugs-by-Shawn-Brackbill-1-1.jpeg\" alt=\"Come la paternit\u00e0 ha cambiato la guerra alla droga | GQ\" width=\"390\" height=\"293\" \/><\/a><figcaption class=\"wp-caption-text\"><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">La guerra alla droga. A sx, il cantante e leader del gruppo Adam Granduciel<\/span><\/span><\/figcaption><\/figure>\r\n<p>&nbsp;<\/p>\r\n<h4>Rimango sbalordito da quella bellezza al punto che, quando arriva il momento del quarto brano, <a href=\"https:\/\/youtu.be\/BijxWQluXE0?si=4cOu-HGdQEGzHRn5\">\u201cUn oceano tra le onde\u201d<\/a>, sento qualcosa dentro di me esplodere, cadere in mille pezzi e ricomporsi in una forma sconosciuta. In quell\u2019epico giro di chitarra, sento i bassi incessanti che scandiscono i battiti del mio cuore, il ritmo della batteria che mi fa staccare i piedi da terra, mentre \u00e8 tutto un turbinio di synth, flanger, ritardi e tremori di chitarra.<\/h4>\r\n<\/div>\r\n<p>&nbsp;<\/p>\r\n<p>&nbsp;<\/p>\r\n<div>\r\n<h3>Quando, nel cuore della canzone, sento questi versi:<\/h3>\r\n<blockquote>\r\n<h3><strong><span class=\"ReferentFragmentdesktop__Highlight-sc-110r0d9-1 jAzSMw\">Sono nel mio momento migliore<br \/>Posso essere pi\u00f9 di un semplice sciocco?<\/span><\/strong><\/h3>\r\n<\/blockquote>\r\n<h3>Sono cos\u00ec senza fiato che, senza rendermene conto, mi ritrovo con le lacrime agli occhi. Nella mia mente scorrono fotogrammi sfocati che evocano luoghi lontani, strapiombi sull'oceano, strade polverose e sconnesse in spazi sconfinati, chilometri da percorrere di corsa in Cadillac verso un altrove che era esattamente il mio sogno da adolescente.<\/h3>\r\n<p>&nbsp;<\/p>\r\n<\/div>\r\n<h2><strong>\u2026Come son finito qui?<\/strong><\/h2>\r\n<p>&nbsp;<\/p>\r\n<h3>Il brano mi ribalta, apre ferite interiori e, contemporaneamente, le sutura. Fisso il vuoto incantato, il mio corpo \u00e8 l\u00ec ma l\u2019anima \u00e8 chiss\u00e0 dove, vibrante d\u2019emozione. Non sento pi\u00f9 che il telefono squilla, che intorno a me si parla ad alta voce e non mi curo molto del fatto che, di tanto in tanto, i colleghi mi interpellino e io risponda loro a monosillabi, svogliatamente, mentre il mio ascolto prosegue, in un ottovolante di sensazioni.<\/h3>\r\n<p>&nbsp;<\/p>\r\n<h3><strong>CONCLUSIONI<\/strong><\/h3>\r\n<h3>Fra momenti intensi e altri pi\u00f9 morbidi, concedendo carezze come pugni allo stomaco, nella cura maniacale dei dettagli e in assoli da pelle d\u2019oca, il disco mantiene il suo splendore in ogni singolo secondo fino al suo epilogo.<\/h3>\r\n<h3>Quando giunge al termine \u00e8 come uscire da un trip, o aprire gli occhi dopo un sonno profondo. Guardi l\u2019orologio e ti accorgi che \u00e8 gi\u00e0 passata un\u2019ora. La routine incombe e devi darti da fare, anche se avresti bisogno di una camera di depressurizzazione simile a quella riservata agli astronauti al ritorno da un viaggio spaziale. Una stanza asettica, dove il sogno abbandona dolcemente il corpo in lenta dissolvenza.<\/h3>\r\n<h3>Questo \u00e8 \u201cLost in the dream\u201d: un viaggio che ti rapisce e ti porta via, trascinandoti in un luogo imprecisato nei meandri della tua mente, sprofondandoti in un limbo di ricordi e di nostalgia di posti che forse nemmeno hai mai visto. E\u2019 come un passaggio improvviso dato da uno sconosciuto verso una meta densa di un significato antico, eppure nuovo, a cui credevi di non essere pi\u00f9 destinato ma che, in cuor tuo, speravi prima o poi di raggiungere ugualmente.<\/h3>\r\n<h3>\u201cLost in the dream\u201d \u00e8, fuor di metafora, un vero e proprio atto d\u2019amore nei confronti della musica. Pochi dischi, al giorno d\u2019oggi, possono diventare un instant-classic e catturarci gi\u00e0 al primo ascolto.<\/h3>\r\n<h3>E\u2019 una pietra miliare del nuovo millennio impressa in un\u2019istantanea non scalfita dall\u2019incedere tempo.<\/h3>\r\n<h3>\u00c8 una pietra miliare del nuovo millennio impressa in un&#039;istantanea inviolata dallo scorrere del tempo.<\/h3>\r\n<h3>Se non lo avete mai ascoltato prima d\u2019ora, fatevi un favore: ascoltatelo il prima possibile.<\/h3>\r\n<h3>Non ve ne pentirete.<\/h3>\r\n<div><a href=\"https:\/\/www.instagram.com\/dreaminvain\/\"><em><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Jack Div<\/span><\/span><\/em><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Milano, marzo 2014, tutto il giorno. Una timida primavera si affaccia alla finestra del terzo piano<\/p>","protected":false},"author":122,"featured_media":7883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-7845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nziria-music-insights"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NZIRIA\u00ae MAGAZINE | Happy 10th Birthday Lost in the Dream<\/title>\n<meta name=\"description\" content=\"LOST IN THE DREAM: COMPIE 10 ANNI IL CAPOLAVORO DEI THE WAR ON DRUGS LOST IN THE DREAM: THE WAR ON DRUGS&#039; MASTERPIECE TURNS 10 YEARS\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nziria.com\/it\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NZIRIA\u00ae MAGAZINE | Happy 10th Birthday Lost in the Dream\" \/>\n<meta property=\"og:description\" content=\"LOST IN THE DREAM: COMPIE 10 ANNI IL CAPOLAVORO DEI THE WAR ON DRUGS LOST IN THE DREAM: THE WAR ON DRUGS&#039; MASTERPIECE TURNS 10 YEARS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nziria.com\/it\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/\" \/>\n<meta property=\"og:site_name\" content=\"NZIRIA\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nziriagroup\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-24T16:11:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-13T00:26:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nziria.com\/wp-content\/uploads\/2024\/04\/happy-birthday-10-lost-in-the-dream-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gaetano Tortora\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/nziria.com\/wp-content\/uploads\/2024\/04\/happy-birthday-10-lost-in-the-dream-.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@NZIRIAgroup\" \/>\n<meta name=\"twitter:site\" content=\"@NZIRIAgroup\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gaetano Tortora\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/\"},\"author\":{\"name\":\"Gaetano Tortora\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#\\\/schema\\\/person\\\/898f6e0595b98589eacf5806ea898d4b\"},\"headline\":\"LOST IN THE DREAM: THE WAR ON DRUGS&#8217; MASTERPIECE TURNS 10 YEARS\",\"datePublished\":\"2024-04-24T16:11:14+00:00\",\"dateModified\":\"2025-09-13T00:26:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/\"},\"wordCount\":1216,\"publisher\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/happy-birthday-10-lost-in-the-dream-.jpg\",\"articleSection\":[\"Music\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/\",\"url\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/\",\"name\":\"NZIRIA\u00ae MAGAZINE | Happy 10th Birthday Lost in the Dream\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/happy-birthday-10-lost-in-the-dream-.jpg\",\"datePublished\":\"2024-04-24T16:11:14+00:00\",\"dateModified\":\"2025-09-13T00:26:29+00:00\",\"description\":\"LOST IN THE DREAM: COMPIE 10 ANNI IL CAPOLAVORO DEI THE WAR ON DRUGS LOST IN THE DREAM: THE WAR ON DRUGS' MASTERPIECE TURNS 10 YEARS\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/happy-birthday-10-lost-in-the-dream-.jpg\",\"contentUrl\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/happy-birthday-10-lost-in-the-dream-.jpg\",\"width\":1600,\"height\":900,\"caption\":\"happy birthday 10 lost in the dream - NZIRIA\u00ae MAGAZINE | Explore Music, Art, and Culture | Latest Reviews & Features\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nziria.com\\\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nziria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Music\",\"item\":\"https:\\\/\\\/nziria.com\\\/category\\\/nziria-music-insights\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LOST IN THE DREAM: THE WAR ON DRUGS&#8217; MASTERPIECE TURNS 10 YEARS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#website\",\"url\":\"https:\\\/\\\/nziria.com\\\/\",\"name\":\"NZIRIA\u00ae Official Cultural Brand and Independent Magazine Since 2004\",\"description\":\"Official Cultural Brand, Magazine &amp; Creative Platform Since 2004\",\"publisher\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/#organization\"},\"alternateName\":\"NZIRIA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nziria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#organization\",\"name\":\"NZIRIA APS\",\"alternateName\":\"NZIRIA Magazine\",\"url\":\"https:\\\/\\\/nziria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-.png\",\"contentUrl\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-.png\",\"width\":512,\"height\":512,\"caption\":\"NZIRIA APS\"},\"image\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nziriagroup\",\"https:\\\/\\\/x.com\\\/NZIRIAgroup\",\"https:\\\/\\\/www.instagram.com\\\/nziria_travel\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/nziriaweb\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NZIRIAgroup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nziria\\\/\",\"https:\\\/\\\/open.spotify.com\\\/playlist\\\/3qYSPpq4ptsARRJN5uE2TH?si=3b09c45eb8ee4a88\",\"https:\\\/\\\/www.tiktok.com\\\/@nziriamagazine?_t=8Vsab2ZriJp&_r=1\",\"https:\\\/\\\/www.instagram.com\\\/nziria_magazine\\\/\",\"https:\\\/\\\/www.instagram.com\\\/nziria__beer\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#\\\/schema\\\/person\\\/898f6e0595b98589eacf5806ea898d4b\",\"name\":\"Gaetano Tortora\",\"url\":\"https:\\\/\\\/nziria.com\\\/it\\\/author\\\/nziriawriter\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RIVISTA NZIRIA\u00ae | Buon decimo compleanno Lost in the Dream","description":"LOST IN THE DREAM: COMPIE 10 ANNI IL CAPOLAVORO DEI THE WAR ON DRUGS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nziria.com\/it\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/","og_locale":"it_IT","og_type":"article","og_title":"NZIRIA\u00ae MAGAZINE | Happy 10th Birthday Lost in the Dream","og_description":"LOST IN THE DREAM: COMPIE 10 ANNI IL CAPOLAVORO DEI THE WAR ON DRUGS LOST IN THE DREAM: THE WAR ON DRUGS' MASTERPIECE TURNS 10 YEARS","og_url":"https:\/\/nziria.com\/it\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/","og_site_name":"NZIRIA\u00ae","article_publisher":"https:\/\/www.facebook.com\/nziriagroup","article_published_time":"2024-04-24T16:11:14+00:00","article_modified_time":"2025-09-13T00:26:29+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/nziria.com\/wp-content\/uploads\/2024\/04\/happy-birthday-10-lost-in-the-dream-.jpg","type":"image\/jpeg"}],"author":"Gaetano Tortora","twitter_card":"summary_large_image","twitter_image":"https:\/\/nziria.com\/wp-content\/uploads\/2024\/04\/happy-birthday-10-lost-in-the-dream-.jpg","twitter_creator":"@NZIRIAgroup","twitter_site":"@NZIRIAgroup","twitter_misc":{"Scritto da":"Gaetano Tortora","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/#article","isPartOf":{"@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/"},"author":{"name":"Gaetano Tortora","@id":"https:\/\/nziria.com\/#\/schema\/person\/898f6e0595b98589eacf5806ea898d4b"},"headline":"LOST IN THE DREAM: THE WAR ON DRUGS&#8217; MASTERPIECE TURNS 10 YEARS","datePublished":"2024-04-24T16:11:14+00:00","dateModified":"2025-09-13T00:26:29+00:00","mainEntityOfPage":{"@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/"},"wordCount":1216,"publisher":{"@id":"https:\/\/nziria.com\/#organization"},"image":{"@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/#primaryimage"},"thumbnailUrl":"https:\/\/nziria.com\/wp-content\/uploads\/2024\/04\/happy-birthday-10-lost-in-the-dream-.jpg","articleSection":["Music"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/","url":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/","name":"RIVISTA NZIRIA\u00ae | Buon decimo compleanno Lost in the Dream","isPartOf":{"@id":"https:\/\/nziria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/#primaryimage"},"image":{"@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/#primaryimage"},"thumbnailUrl":"https:\/\/nziria.com\/wp-content\/uploads\/2024\/04\/happy-birthday-10-lost-in-the-dream-.jpg","datePublished":"2024-04-24T16:11:14+00:00","dateModified":"2025-09-13T00:26:29+00:00","description":"LOST IN THE DREAM: COMPIE 10 ANNI IL CAPOLAVORO DEI THE WAR ON DRUGS","breadcrumb":{"@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/#primaryimage","url":"https:\/\/nziria.com\/wp-content\/uploads\/2024\/04\/happy-birthday-10-lost-in-the-dream-.jpg","contentUrl":"https:\/\/nziria.com\/wp-content\/uploads\/2024\/04\/happy-birthday-10-lost-in-the-dream-.jpg","width":1600,"height":900,"caption":"happy birthday 10 lost in the dream - NZIRIA\u00ae MAGAZINE | Explore Music, Art, and Culture | Latest Reviews & Features"},{"@type":"BreadcrumbList","@id":"https:\/\/nziria.com\/lost-in-the-dream-compie-10-anni-il-capolavoro-dei-the-war-on-drugs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nziria.com\/"},{"@type":"ListItem","position":2,"name":"Music","item":"https:\/\/nziria.com\/category\/nziria-music-insights\/"},{"@type":"ListItem","position":3,"name":"LOST IN THE DREAM: THE WAR ON DRUGS&#8217; MASTERPIECE TURNS 10 YEARS"}]},{"@type":"WebSite","@id":"https:\/\/nziria.com\/#website","url":"https:\/\/nziria.com\/","name":"NZIRIA\u00ae Marchio culturale ufficiale e rivista indipendente dal 2004","description":"Marchio culturale ufficiale, rivista e piattaforma creativa dal 2004","publisher":{"@id":"https:\/\/nziria.com\/#organization"},"alternateName":"NZIRIA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nziria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nziria.com\/#organization","name":"NZIRIA APS","alternateName":"NZIRIA Magazine","url":"https:\/\/nziria.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nziria.com\/#\/schema\/logo\/image\/","url":"https:\/\/nziria.com\/wp-content\/uploads\/2026\/04\/logo-.png","contentUrl":"https:\/\/nziria.com\/wp-content\/uploads\/2026\/04\/logo-.png","width":512,"height":512,"caption":"NZIRIA APS"},"image":{"@id":"https:\/\/nziria.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nziriagroup","https:\/\/x.com\/NZIRIAgroup","https:\/\/www.instagram.com\/nziria_travel\/","https:\/\/www.pinterest.com\/nziriaweb\/","https:\/\/www.youtube.com\/user\/NZIRIAgroup","https:\/\/www.linkedin.com\/company\/nziria\/","https:\/\/open.spotify.com\/playlist\/3qYSPpq4ptsARRJN5uE2TH?si=3b09c45eb8ee4a88","https:\/\/www.tiktok.com\/@nziriamagazine?_t=8Vsab2ZriJp&_r=1","https:\/\/www.instagram.com\/nziria_magazine\/","https:\/\/www.instagram.com\/nziria__beer\/"]},{"@type":"Person","@id":"https:\/\/nziria.com\/#\/schema\/person\/898f6e0595b98589eacf5806ea898d4b","name":"Gaetano Tortora","url":"https:\/\/nziria.com\/it\/author\/nziriawriter\/"}]}},"_links":{"self":[{"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/posts\/7845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/users\/122"}],"replies":[{"embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/comments?post=7845"}],"version-history":[{"count":34,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/posts\/7845\/revisions"}],"predecessor-version":[{"id":7956,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/posts\/7845\/revisions\/7956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/media\/7883"}],"wp:attachment":[{"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/media?parent=7845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/categories?post=7845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/tags?post=7845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}