{"id":2873,"date":"2020-03-30T17:39:37","date_gmt":"2020-03-30T17:39:37","guid":{"rendered":"https:\/\/nziria.com\/?p=2873"},"modified":"2025-11-10T22:35:24","modified_gmt":"2025-11-10T21:35:24","slug":"stop-covid-19","status":"publish","type":"post","link":"https:\/\/nziria.com\/it\/stop-covid-19\/","title":{"rendered":"Speranze per il Covid-19?"},"content":{"rendered":"<h4 style=\"text-align: left;\"><em>Ci sono delle vere speranze di uscita dal covid19? Numerose ricerche ipotizzano una connessione tra coronavirus, ambiente e stagionalit\u00e0.<\/em><\/h4>\n<p style=\"text-align: left;\"><a href=\"http:\/\/nziria.com\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-2875 size-medium\" src=\"https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria-300x251.png\" alt=\"covid 19\" width=\"300\" height=\"251\" srcset=\"https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria-300x251.png 300w, https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria-600x503.png 600w, https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria-768x644.png 768w, https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria-750x629.png 750w, https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria-400x335.png 400w, https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria-430x360.png 430w, https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria-150x126.png 150w, https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria-100x84.png 100w, https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/Hopes-for-Covid-19_nziria.png 940w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Sulla base di esperienze passate con altri virus che infettano le vie respiratorie, si \u00e8 dimostrato che nella nostra area climatica mediterranea <strong>le infezioni diminuiscono con l&#039;arrivo dell&#039;estate<\/strong>. <span style=\"color: #000000;\">Il Covid-19 potrebbe quindi reagire allo stesso modo di altri virus ai cambiamenti climatici?<\/span><\/p>\n<p style=\"text-align: left;\">Purtroppo sono supposizioni. Non ci sono ancora prove concrete per cui il bel tempo possa effettivamente debellare l&#039;epidemia. Inoltre, come afferma l&#039;analista Sara Mazzilli, dottoranda in Data Science applicata all&#039;epidemiologia alla Scuola Normale Superiore di Pisa, seppure esistesse una correlazione tra <strong>coronavirus e stagione estiva<\/strong>, non dobbiamo dimenticare che entriamo in contatto per la prima volta con il nuovo virus e che pertanto non abbiamo ancora sviluppato gli <strong>anticorpi<\/strong> adeguati per difenderci.<\/p>\n<p style=\"text-align: left;\">L&#039;unica cosa che certamente possiamo immaginare \u00e8 che da sempre il clima e soprattutto l&#039;esposizione al sole, influenzano il nostro <strong>sistema immunitario<\/strong>, debilitandolo o rafforzandolo. In particolare, secondo diversi immunologi, i livelli di <strong>vitamina D<\/strong> sono direttamente proporzionali alla resistenza del sistema immunitario contro virus e batteri.<\/p>\n<h5 style=\"text-align: left;\">I ricercatori dell&#039;Istituto di virologia umana dell&#039;Universit\u00e0 del Maryland hanno messo <strong>a confronto i paesi focolai<\/strong> quali Madrid, Parigi, Milano, Qom, Wuhan, Tokyo, Daegu, evidenziando diversi punti in comune: latitudine, temperatura, umidit\u00e0 e livelli di inquinamento. Secondo queste ricerche, le zone di massima diffusione si trovano nella fascia compresa tra 30 e 50 gradi a Nord, le temperature medie invernali si registrano tra i 5 e gli 11 gradi centigradi, il livello di umidit\u00e0 medio tra il 47 e il 75% \u00e8 tassi di inquinamento risultano notevoli.<\/h5>\n<p style=\"text-align: left;\">Anche secondo la giornalista Mariella Bussolati, ci sarebbe una \u201ccintura verde\u201d in cui il coronavirus si diffonde di pi\u00f9. <strong><span style=\"color: #017b93;\"><a style=\"color: #017b93;\" href=\"https:\/\/it.businessinsider.com\/ci-sarebbe-una-cintura-del-coronaviris-una-fascia-climatica-in-cui-si-sviluppa-di-piu-lestate-potrebbe-migliorare-la-situazione\/\">&gt;&gt;&gt; Leggi l&#039;articolo.<\/a><\/span>\u00a0<\/strong><\/p>\n<p style=\"text-align: left;\">Moltissime sono le ricerche che provano a capire se concretamente l&#039;estate ci aiuter\u00e0 a vincere il virus. Indubbiamente trascorrere pi\u00f9 tempo all&#039;aperto significa evitare ambienti chiusi e affollati che favoriscono la circolazione dei microrganismi responsabili di infezioni. Inoltre \u00e8 noto che respirare l&#039;aria di <strong>cavalla<\/strong> e le sue sostanze oligominerali rendono le nostre difese immunitarie pi\u00f9 efficaci. I sali minerali come iodio, magnesio, cloruro di sodio, calcio e potassio, liberano le vie respiratorie agendo da mucolitici e antinfiammatori.<\/p>\n<p style=\"text-align: left;\">Con una semplice passeggiata in riva al mare, otteniamo straordinari benefici per allergie, sinusiti, asma, raffreddore, nonch\u00e9 per problematiche causate da fumo o agenti chimici.<\/p>\n<p style=\"text-align: left;\">Ma tra i benefici del mare, ci sono anche quelli esercitati sulla mente, sullo stress e il tono dell&#039;umore. Rilassarsi al sole ci permette di recuperare le energie, di svagarci e allentare le tensioni, di sentirci pi\u00f9 sereni per affrontare la quotidianit\u00e0.<\/p>\n<p style=\"text-align: left;\">Usiamo questo tempo prezioso per <strong>riflettere<\/strong> sulla nostra salute e sull&#039;ambiente in cui viviamo, di cui probabilmente, abbiamo perso il valore. <strong>Ambiente e salute<\/strong> sono facce della stessa medaglia.<\/p>\n<p style=\"text-align: left;\"><strong>Mariella Ciccarino\u00a0<\/strong><\/p>\n<p><strong><span style=\"color: #017b93;\">Versione inglese \u21d3<\/span><\/strong><\/p>\n<h4><span style=\"color: #000000;\"><strong>Speranze per il Covid-19?<\/strong><\/span><\/h4>\n<p><span style=\"font-weight: 400;\">Numerose ricerche ipotizzano una connessione tra coronavirus, ambiente e stagionalit\u00e0. <\/span><span style=\"font-weight: 400;\">L\u2019esperienza passata si basa sugli altri virus che infettano le vie respiratorie, \u00e8 stato dimostrato che nella nostra zona a clima mediterraneo i contagi diminuiscono con l\u2019arrivo dell\u2019estate.<\/span><\/p>\n<p><span style=\"color: #000000;\"><strong>Il Covid-19 potrebbe reagire allo stesso modo degli altri virus ai cambiamenti climatici?<\/strong><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Purtroppo sono postulati. Non ci sono ancora prove concrete che il bel tempo possa effettivamente cancellare l\u2019epidemia. <\/span><span style=\"font-weight: 400;\">Inoltre, dice l\u2019analista Sara Mazzilli, dottoranda in Data Science applicata all\u2019epidemiologia alla Scuola Normale Superiore di Pisa, anche se ci fosse una correlazione tra coronavirus e stagione estiva, non dobbiamo dimenticare che ne entriamo in contatto per la prima volta con il nuovo virus e che quindi non abbiamo ancora sviluppato gli anticorpi adeguati per difenderci.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L\u2019unica cosa che possiamo certamente immaginare \u00e8 che il clima e soprattutto l\u2019esposizione al sole influenzano da sempre il nostro sistema immunitario, debilitandolo o rafforzandolo. In particolare, secondo diversi immunologi, i livelli di vitamina D sono direttamente proporzionali alla resistenza del sistema immunitario contro virus e batteri.<\/span><\/p>\n<h5><strong>I ricercatori dell\u2019Istituto di Virologia Umana dell\u2019Universit\u00e0 del Maryland hanno confrontato Paesi focolai come Madrid, Parigi, Milano, Qom, Wuhan, Tokyo, Daegu, evidenziando diversi punti in comune: latitudine, temperature, umidit\u00e0 e livelli di inquinamento. Secondo queste ricerche, le aree di massima diffusione sono comprese tra 30 e 50 gradi al Nord, le temperature medie invernali sono comprese tra 5 e 11 gradi centigradi, l&#039;umidit\u00e0 media tra 47 e 75% e i tassi di inquinamento sono notevoli.<\/strong><\/h5>\n<p><span style=\"font-weight: 400;\">Anche secondo la giornalista Mariella Bussolati esisterebbe una \u201ccintura verde\u201d in cui il Covid 19 si diffonde maggiormente.<span style=\"color: #017b93;\"><strong> <a style=\"color: #017b93;\" href=\"https:\/\/it.businessinsider.com\/ci-sarebbe-una-cintura-del-coronaviris-una-fascia-climatica-in-cui-si-sviluppa-di-piu-lestate-potrebbe-migliorare-la-situazione\/\">&gt;&gt;&gt; Vai all&#039;articolo<\/a>\u00a0<\/strong><\/span><\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sono tante le ricerche che cercano di capire se effettivamente l\u2019estate ci aiuter\u00e0 a vincere il virus. Trascorrere pi\u00f9 tempo all\u2019aria aperta significa senza dubbio evitare ambienti chiusi e affollati che favoriscono la circolazione dei microrganismi responsabili delle infezioni. \u00c8 noto inoltre che respirare l&#039;aria di mare e i suoi oligoelementi rende pi\u00f9 efficaci le nostre difese immunitarie. Sali minerali come iodio, magnesio, cloruro di sodio, calcio e potassio, liberano le vie respiratorie agendo come mucolitici e antinfiammatori.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con una semplice passeggiata in riva al mare otteniamo straordinari benefici contro allergie, sinusiti, asma, raffreddore, oltre che per problemi causati dal fumo o dagli agenti chimici.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ma tra i benefici del mare ci sono anche quelli esercitati sulla mente, sullo stress e sull\u2019umore. Rilassarsi al sole ci permette di recuperare le energie, di rilassarci e allentare le tensioni, di sentirci pi\u00f9 sereni per affrontare la vita di tutti i giorni.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Usiamo questo tempo prezioso per riflettere sulla nostra salute e sull&#039;ambiente in cui viviamo, di cui probabilmente abbiamo perso valore. Ambiente e salute sono facce della stessa medaglia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><strong>Casa della squadra NZIRIA<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #017b93;\">Versione tedesca \u21d3<\/span><\/strong><\/p>\n<h3 style=\"text-align: left;\">Protezione contro il Covid-19?<\/h3>\n<p style=\"text-align: left;\">Zahlreiche Studien vermuten einen Zusammenhang zwischen Coronavirus, Umwelt und<br \/>\nStagione. Aus den Erfahrungen der Vergangenheit mit anderen Viren, die die Atemwege infizieren,<br \/>\ngeht hervor, dass in unserem mediterranen Klimagebiet die Infektionen mit der Ankunft<br \/>\ndes Sommers abnehmen. K\u00f6nnte Covid-19 anche come andere Viren auf den Klimawandel reagieren?<\/p>\n<p style=\"text-align: left;\">Leider istdas eine Vermutung. Es gibt immer noch keine konkreten Beweise daf\u00fcr, dass gutes Wetter die Epidemie<br \/>\ntats\u00e4chlich ausrotten kann. Come die Analytikerin Sara Mazzilli, Doktorandin in Datenwissenschaften, die sich an der<br \/>\nScuola Normale Superiore di Pisa per l&#039;epidemiologia beworben hat, sagt, d\u00fcrfen wir,<br \/>\novviamente c&#039;\u00e8 una correlazione tra il coronavirus e la stagione estiva,<br \/>\nnon vergessen, dass wir zum ersten Mal mit dem new Virus in Kontakt sind and daher<br \/>\nnoch nicht die geeigneten Antik\u00f6rper zur Verteidigung entwickelt haben.<\/p>\n<p style=\"text-align: left;\">Das einzige, was wir uns sicher vorstellen k\u00f6nnen, ist, dass das Klima e vor allem die<br \/>\nL&#039;integrazione del sistema immunitario nel nostro sistema immunitario \u00e8 sempre influenzata ed \u00e8 responsabile<br \/>\noder gest\u00e4rkt hat.<\/p>\n<h5 style=\"text-align: left;\">Forscher des Instituts f\u00fcr Humanvirologie der Universit\u00e4t Maryland verglichen Mistl\u00e4nder<br \/>\ncome Madrid, Parigi, Mailand, Qom, Wuhan, Tokio e Daegu<br \/>\ne hoben dabei mehrere Gemeinsamkeiten hervor: Breitengrad, Temperaturen,<br \/>\nFeuchtigkeit e Verschmutzungsgrad.<\/h5>\n<p style=\"text-align: left;\">Nach diesen Untersuchungen liegen die Gebiete mit der gr\u00f6\u00dften Verbreitung im Bereich<br \/>\nzwischen 30und 50 Grad n\u00f6rdlicher Breite, die durchschnittlichen Wintertemperaturen lieg<br \/>\nen zwischen 5 und 11 Grad Celsius, die durchschnittliche Luftfeuchtigkeit zwischen 47<br \/>\nund 75% e la velocit\u00e0 di commutazione sono migliori.<\/p>\n<h4 style=\"text-align: left;\">Auch laut der Journalistin Mariella Bussolati gibt es einen G\u00fcrtel G\u00fcrtel, in dem<br \/>\nsich das Coronavirus st\u00e4rker ausbreitet. <span style=\"color: #017b93;\"><a style=\"color: #017b93;\" href=\"https:\/\/it.businessinsider.com\/ci-sarebbe-una-cintura-del-coronaviris-una-fascia-climatica-in-cui-si-sviluppa-di-piu-lestate-potrebbe-migliorare-la-situazione\/\">&gt;&gt;&gt;Leggi l&#039;articolo<\/a><\/span><\/h4>\n<p style=\"text-align: left;\">Es gibt eine Menge Forschung, die versucht zu verstehen, ob der Summer uns tats\u00e4chlich<br \/>\nhelfen wird, das Virus zu gewinnen.<\/p>\n<p style=\"text-align: left;\">Zweifellos bedeutet mehr Zeit im Freien zu verbringen, geschlossene und \u00fcberf\u00fcllte Umge<br \/>\nBungen zu vermeiden, die die Zirkulation der f\u00fcr Infektionen verantwortlichen<br \/>\nI microrganismi si formano.<br \/>\n\u00c8 anche chiaro che gli uomini del mare e i loro oligominali<br \/>\nSubstanzen unsere Immunabwehr wirksamer macht.<br \/>\nMineralsalze come Jod, Magnesium, Natrium Chlorid, Kalzium e Kalium befreien die Atem<br \/>\nwege, indem sie als Mukolytika und Entz\u00fcndungshemmer wirken.<\/p>\n<p style=\"text-align: left;\">Uno spazio einfacher am Meer porta uns au\u00dferordentliche Vorteile bei Allergien,<br \/>\nSinusite, asma, disturbi e problemi causati dalla rabbia o dai prodotti chimici<br \/>\nverursacht werden.<\/p>\n<p style=\"text-align: left;\">Aber zu den Vorteilen des Meeres geh\u00f6ren auch die, die sich auf den Geist, den Stress<br \/>\ne die Stimmung auswirken. Das Entspannen in der Sonne erm\u00f6glicht es nois,<br \/>\nla nostra energia zur\u00fcckzugewinnen, Spannungen abzubauen e dem Alltag gelassener<br \/>\nper iniziare.<br \/>\nWer nutzen diese costbare Zeit, um \u00fcber our Gesundheit and die Umwelt, in der wir<br \/>\nleben und deren Wert wir wahrscheinlich verloren haben, nachzudenken. Mondo e ambiente<br \/>\nGesundheit sind die Seiten derselben Medaille.<\/p>\n<p style=\"text-align: left;\"><strong>Casa della squadra NZIRIA<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Ci sono delle vere speranze di uscita dal covid19? Numerose ricerche ipotizzano una connessione tra<\/p>","protected":false},"author":1,"featured_media":2896,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-2873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nziria-music-insights"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hopes for Covid-19? NZIRIA - Social Media Magazine<\/title>\n<meta name=\"description\" content=\"Il Covid-19 potrebbe quindi reagire allo stesso modo di altri virus ai cambiamenti climatici?Purtroppo sono supposizioni. Non ci sono ancora\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nziria.com\/it\/stop-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hopes for Covid-19? NZIRIA - Social Media Magazine\" \/>\n<meta property=\"og:description\" content=\"Il Covid-19 potrebbe quindi reagire allo stesso modo di altri virus ai cambiamenti climatici?Purtroppo sono supposizioni. Non ci sono ancora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nziria.com\/it\/stop-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"NZIRIA\u00ae\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nziriagroup\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/nziriagroup\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-30T17:39:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-10T21:35:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/stop-covid-19-nziria-coronavirus-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"NZIRIA APS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@NZIRIAgroup\" \/>\n<meta name=\"twitter:site\" content=\"@NZIRIAgroup\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"NZIRIA APS\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/\"},\"author\":{\"name\":\"NZIRIA APS\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#\\\/schema\\\/person\\\/15ec4037bb01ba8f27b5be86004e2e2c\"},\"headline\":\"Speranze per il Covid &#8211; 19 ?\",\"datePublished\":\"2020-03-30T17:39:37+00:00\",\"dateModified\":\"2025-11-10T21:35:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/\"},\"wordCount\":1411,\"publisher\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/stop-covid-19-nziria-coronavirus-1.png\",\"articleSection\":[\"Music\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/\",\"url\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/\",\"name\":\"Hopes for Covid-19? NZIRIA - Social Media Magazine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/stop-covid-19-nziria-coronavirus-1.png\",\"datePublished\":\"2020-03-30T17:39:37+00:00\",\"dateModified\":\"2025-11-10T21:35:24+00:00\",\"description\":\"Il Covid-19 potrebbe quindi reagire allo stesso modo di altri virus ai cambiamenti climatici?Purtroppo sono supposizioni. Non ci sono ancora\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/stop-covid-19-nziria-coronavirus-1.png\",\"contentUrl\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/stop-covid-19-nziria-coronavirus-1.png\",\"width\":1200,\"height\":600,\"caption\":\"covid 19\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nziria.com\\\/stop-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nziria.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Speranze per il Covid &#8211; 19 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#website\",\"url\":\"https:\\\/\\\/nziria.com\\\/\",\"name\":\"NZIRIA\u00ae Official Cultural Brand and Independent Magazine Since 2004\",\"description\":\"Official Cultural Brand, Magazine &amp; Creative Platform Since 2004\",\"publisher\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/#organization\"},\"alternateName\":\"NZIRIA\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nziria.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#organization\",\"name\":\"NZIRIA APS\",\"alternateName\":\"NZIRIA MAGAZINE\",\"url\":\"https:\\\/\\\/nziria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-.png\",\"contentUrl\":\"https:\\\/\\\/nziria.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/logo-.png\",\"width\":512,\"height\":512,\"caption\":\"NZIRIA APS\"},\"image\":{\"@id\":\"https:\\\/\\\/nziria.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/nziriagroup\",\"https:\\\/\\\/x.com\\\/NZIRIAgroup\",\"https:\\\/\\\/www.instagram.com\\\/nziria_travel\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/nziriaweb\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/NZIRIAgroup\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nziria\\\/\",\"https:\\\/\\\/open.spotify.com\\\/playlist\\\/3qYSPpq4ptsARRJN5uE2TH?si=3b09c45eb8ee4a88\",\"https:\\\/\\\/www.tiktok.com\\\/@nziriamagazine?_t=8Vsab2ZriJp&_r=1\",\"https:\\\/\\\/www.instagram.com\\\/nziria_magazine\\\/\",\"https:\\\/\\\/www.instagram.com\\\/nziria__beer\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/nziria.com\\\/#\\\/schema\\\/person\\\/15ec4037bb01ba8f27b5be86004e2e2c\",\"name\":\"NZIRIA APS\",\"sameAs\":[\"http:\\\/\\\/nziria.com\",\"https:\\\/\\\/www.facebook.com\\\/nziriagroup\",\"https:\\\/\\\/www.instagram.com\\\/nziria_magazine\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/nziria\\\/\",\"https:\\\/\\\/uk.pinterest.com\\\/nziriagroup\"],\"url\":\"https:\\\/\\\/nziria.com\\\/it\\\/author\\\/nziriadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Speranze per il Covid-19? NZIRIA - Rivista di social media","description":"Il Covid-19 potrebbe quindi reagire allo stesso modo di altri virus ai cambiamenti climatici? Purtroppo sono supposizioni. Non ci sono ancora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nziria.com\/it\/stop-covid-19\/","og_locale":"it_IT","og_type":"article","og_title":"Hopes for Covid-19? NZIRIA - Social Media Magazine","og_description":"Il Covid-19 potrebbe quindi reagire allo stesso modo di altri virus ai cambiamenti climatici?Purtroppo sono supposizioni. Non ci sono ancora","og_url":"https:\/\/nziria.com\/it\/stop-covid-19\/","og_site_name":"NZIRIA\u00ae","article_publisher":"https:\/\/www.facebook.com\/nziriagroup","article_author":"https:\/\/www.facebook.com\/nziriagroup","article_published_time":"2020-03-30T17:39:37+00:00","article_modified_time":"2025-11-10T21:35:24+00:00","og_image":[{"width":1200,"height":600,"url":"https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/stop-covid-19-nziria-coronavirus-1.png","type":"image\/png"}],"author":"NZIRIA APS","twitter_card":"summary_large_image","twitter_creator":"@NZIRIAgroup","twitter_site":"@NZIRIAgroup","twitter_misc":{"Scritto da":"NZIRIA APS","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/nziria.com\/stop-covid-19\/#article","isPartOf":{"@id":"https:\/\/nziria.com\/stop-covid-19\/"},"author":{"name":"NZIRIA APS","@id":"https:\/\/nziria.com\/#\/schema\/person\/15ec4037bb01ba8f27b5be86004e2e2c"},"headline":"Speranze per il Covid &#8211; 19 ?","datePublished":"2020-03-30T17:39:37+00:00","dateModified":"2025-11-10T21:35:24+00:00","mainEntityOfPage":{"@id":"https:\/\/nziria.com\/stop-covid-19\/"},"wordCount":1411,"publisher":{"@id":"https:\/\/nziria.com\/#organization"},"image":{"@id":"https:\/\/nziria.com\/stop-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/stop-covid-19-nziria-coronavirus-1.png","articleSection":["Music"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/nziria.com\/stop-covid-19\/","url":"https:\/\/nziria.com\/stop-covid-19\/","name":"Speranze per il Covid-19? NZIRIA - Rivista di social media","isPartOf":{"@id":"https:\/\/nziria.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nziria.com\/stop-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/nziria.com\/stop-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/stop-covid-19-nziria-coronavirus-1.png","datePublished":"2020-03-30T17:39:37+00:00","dateModified":"2025-11-10T21:35:24+00:00","description":"Il Covid-19 potrebbe quindi reagire allo stesso modo di altri virus ai cambiamenti climatici? Purtroppo sono supposizioni. Non ci sono ancora","breadcrumb":{"@id":"https:\/\/nziria.com\/stop-covid-19\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nziria.com\/stop-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nziria.com\/stop-covid-19\/#primaryimage","url":"https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/stop-covid-19-nziria-coronavirus-1.png","contentUrl":"https:\/\/nziria.com\/wp-content\/uploads\/2020\/03\/stop-covid-19-nziria-coronavirus-1.png","width":1200,"height":600,"caption":"covid 19"},{"@type":"BreadcrumbList","@id":"https:\/\/nziria.com\/stop-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nziria.com\/"},{"@type":"ListItem","position":2,"name":"Speranze per il Covid &#8211; 19 ?"}]},{"@type":"WebSite","@id":"https:\/\/nziria.com\/#website","url":"https:\/\/nziria.com\/","name":"NZIRIA\u00ae Marchio culturale ufficiale e rivista indipendente dal 2004","description":"Marchio culturale ufficiale, rivista e piattaforma creativa dal 2004","publisher":{"@id":"https:\/\/nziria.com\/#organization"},"alternateName":"NZIRIA","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nziria.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/nziria.com\/#organization","name":"NZIRIA APS","alternateName":"NZIRIA MAGAZINE","url":"https:\/\/nziria.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/nziria.com\/#\/schema\/logo\/image\/","url":"https:\/\/nziria.com\/wp-content\/uploads\/2026\/04\/logo-.png","contentUrl":"https:\/\/nziria.com\/wp-content\/uploads\/2026\/04\/logo-.png","width":512,"height":512,"caption":"NZIRIA APS"},"image":{"@id":"https:\/\/nziria.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/nziriagroup","https:\/\/x.com\/NZIRIAgroup","https:\/\/www.instagram.com\/nziria_travel\/","https:\/\/www.pinterest.com\/nziriaweb\/","https:\/\/www.youtube.com\/user\/NZIRIAgroup","https:\/\/www.linkedin.com\/company\/nziria\/","https:\/\/open.spotify.com\/playlist\/3qYSPpq4ptsARRJN5uE2TH?si=3b09c45eb8ee4a88","https:\/\/www.tiktok.com\/@nziriamagazine?_t=8Vsab2ZriJp&_r=1","https:\/\/www.instagram.com\/nziria_magazine\/","https:\/\/www.instagram.com\/nziria__beer\/"]},{"@type":"Person","@id":"https:\/\/nziria.com\/#\/schema\/person\/15ec4037bb01ba8f27b5be86004e2e2c","name":"NZIRIA APS","sameAs":["http:\/\/nziria.com","https:\/\/www.facebook.com\/nziriagroup","https:\/\/www.instagram.com\/nziria_magazine\/","https:\/\/www.linkedin.com\/company\/nziria\/","https:\/\/uk.pinterest.com\/nziriagroup"],"url":"https:\/\/nziria.com\/it\/author\/nziriadmin\/"}]}},"_links":{"self":[{"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/posts\/2873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/comments?post=2873"}],"version-history":[{"count":2,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/posts\/2873\/revisions"}],"predecessor-version":[{"id":8279,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/posts\/2873\/revisions\/8279"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/media\/2896"}],"wp:attachment":[{"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/media?parent=2873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/categories?post=2873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nziria.com\/it\/wp-json\/wp\/v2\/tags?post=2873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}